{"id":369134,"date":"2026-08-07T08:51:28","date_gmt":"2026-08-07T06:51:28","guid":{"rendered":"https:\/\/technikratlive.hw.ag\/produkt\/esd-dauerfersenband-klettverschluss-1mohm-widerstand-schwarz-blau-rot\/"},"modified":"2026-09-01T21:29:14","modified_gmt":"2026-09-01T19:29:14","slug":"esd-dauerfersenband-klettverschluss-1mohm-widerstand-schwarz-blau-rot","status":"publish","type":"product","link":"https:\/\/technikrat.de\/en\/produkt\/esd-dauerfersenband-klettverschluss-1mohm-widerstand-schwarz-blau-rot\/","title":{"rendered":"ESD continuous heel strap, Velcro fastener, 1MOhm resistance, black\/blue\/red"},"content":{"rendered":"<p>ESD permanent heel strap with Velcro fastener<\/p>\n<p>for normal street shoes with flat heels<\/p>\n<p>black\/blue\/red<\/p>\n<p>Safety resistance: 1MOhm<\/p>","protected":false},"excerpt":{"rendered":"<p>ESD permanent heel strap with Velcro fastener for normal street shoes with flat heels black\/blue\/red Safety resistance: 1MOhm<\/p>\n","protected":false},"featured_media":658528,"template":"","meta":{"ep_exclude_from_search":false},"product_cat":[133],"product_tag":[],"class_list":{"0":"post-369134","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schuhe","7":"product_shipping_class-postwarenpost-individuell","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/product\/369134"}],"collection":[{"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/media\/658528"}],"wp:attachment":[{"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/media?parent=369134"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/product_cat?post=369134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/technikrat.de\/en\/wp-json\/wp\/v2\/product_tag?post=369134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}